{"id":7651,"date":"2014-07-30T17:12:05","date_gmt":"2014-07-30T15:12:05","guid":{"rendered":"http:\/\/realschule-eching.de\/cms\/?page_id=7651"},"modified":"2021-10-12T16:16:44","modified_gmt":"2021-10-12T14:16:44","slug":"loesungswegweiser-fuer-eltern","status":"publish","type":"page","link":"https:\/\/www.realschule-eching.de\/cms\/fuer-eltern\/loesungswegweiser-fuer-eltern\/","title":{"rendered":"L\u00f6sungswegweiser f\u00fcr Eltern"},"content":{"rendered":"<p><a href=\"https:\/\/realschule-eching.de\/cms\/downloads\/Loesungswegweiser.pdf\">L\u00f6sungswegweiser als PDF-Download<\/a><\/p>\n<p>Dort wo viele Menschen aufeinander treffen, &#8222;menschelt&#8220; es ganz einfach. Da kann es auch einmal sein, dass unterschiedliche Meinungen und Ansichten aufeinandertreffen. Selbst wenn Meinungsverschiedenheiten nicht an der Tagesordnung stehen, k\u00f6nnen sie vor allem dann sehr unangenehm sein, wenn sie Ihr eigenes Kind betreffen.<\/p>\n<p><strong> In unserer Schulgemeinschaft wollen wir Probleme dort behandeln und l\u00f6sen, wo sie entstehen &#8211; bei uns an der Schule und zwar in erster Linie zwischen den beteiligten Personen.<\/strong><br \/>\nZahlreiche Probleme basieren auf Missverst\u00e4ndnissen und falschen Informationen. Damit diese nicht gleich &#8222;eskalieren&#8220;, haben wir Ihnen im Folgenden einige Tipps zusammengestellt, die Sie bitte immer (in dieser Reihenfolge) ber\u00fccksichtigen.<\/p>\n<p><strong>1. Haben Sie oder Ihr Kind schon mit der betreffenden Lehrkraft gesprochen?<\/strong> Viele Missverst\u00e4ndnisse k\u00f6nnen so am schnellsten aus dem Weg ger\u00e4umt werden! Zur Vorbereitung empfehlen wir Ihnen, dass Sie vorher gemeinsam mit Ihrem Kind folgende Fragen f\u00fcr sich kl\u00e4ren:<\/p>\n<ul>\n<li>Woran w\u00fcrde Ihr Kind erkennen, dass die Probleme gel\u00f6st sind?<\/li>\n<li>Woran w\u00fcrden Sie als ELTERN erkennen, dass die Probleme gel\u00f6st sind?<\/li>\n<li>Welchen Handlungsspielraum nutzt Ihr Kind aktuell, um das Problem zu l\u00f6sen?<\/li>\n<li>Welche Unterst\u00fctzung ben\u00f6tigt Ihr Kind dabei von Ihnen als Eltern und von der Lehrkraft?<\/li>\n<\/ul>\n<p><strong>2. Haben Sie oder hat Ihr Kind schon mit der Klassenleitung gesprochen?<\/strong> Wenn dies schon geschehen ist oder nicht m\u00f6glich erscheint, hilft meist ein vertrauliches Gespr\u00e4ch mit einer Lehrkraft des Vertrauens weiter (in der Regel eine der Verbindungslehrkr\u00e4fte).<\/p>\n<p><strong> 3.<\/strong> Gerade bei Fragen und Problemen, die die Schullaufbahn Ihres Kindes betreffen (z.B. wenn bei schlechten Schulleistungen das Wiederholen der Jahrgangsstufe &#8222;droht&#8220; oder ein Schulwechsel angedacht wird), empfehlen wir Ihnen, rechtzeitig unsere <strong>Beratungslehrkraft<\/strong> Frau Feyler zu konsultieren.<br \/>\n<strong>4.<\/strong> Falls diese Gespr\u00e4che schon stattgefunden haben, k\u00f6nnen Sie um einen <strong>Gespr\u00e4chstermin mit der Schulleitung<\/strong> und der betreffenden Lehrkraft bitten. Andernfalls wird Sie die Schulleitung wieder an die Lehrkraft verweisen, mit der zun\u00e4chst \u00fcber das Problem gesprochen werden muss.<\/p>\n<p><strong>5.<\/strong> Wenn zwischen Ihnen, der Lehrkraft und der Schulleitung schon ein Gespr\u00e4ch stattgefunden hat und Sie davon \u00fcberzeugt sind, dass Ihrem Kind und\/oder Ihnen nach wie vor Unrecht widerfahren ist, dann k\u00f6nnen Sie bei der Schule schriftlich eine so genannte &#8222;<strong>Aufsichtsbeschwerde<\/strong>&#8220; erheben. Sie sollten Ihr Anliegen so formulieren, dass daraus auch f\u00fcr die \u00fcbergeordneten Dienststellen der Sachverhalt eindeutig hervorgeht. Wenn wir als Schule dieser Aufsichtsbeschwerde nicht abhelfen (k\u00f6nnen), wird Ihre Beschwerde mit einer Stellungnahme der Schule an den zust\u00e4ndigen Ministerialbeauftragten f\u00fcr die Realschulen in Oberbayern-Ost (RSD Wilhelm K\u00fcrzeder, (www.realschule.bayern.de\/obo) zur Entscheidung weitergeleitet.<\/p>\n<p>Wir beraten Sie gerne bei weiteren rechtlichen Fragen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u00f6sungswegweiser als PDF-Download Dort wo viele Menschen aufeinander treffen, &#8222;menschelt&#8220; es ganz einfach. Da kann es auch einmal sein, dass unterschiedliche Meinungen und Ansichten aufeinandertreffen. Selbst wenn Meinungsverschiedenheiten nicht an der Tagesordnung stehen, k\u00f6nnen sie vor allem dann sehr unangenehm sein, wenn sie Ihr eigenes Kind betreffen. In unserer Schulgemeinschaft wollen wir Probleme dort behandeln [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":7643,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-7651","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7651"}],"collection":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/comments?post=7651"}],"version-history":[{"count":2,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7651\/revisions"}],"predecessor-version":[{"id":19765,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7651\/revisions\/19765"}],"up":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7643"}],"wp:attachment":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media?parent=7651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}