{"id":7685,"date":"2014-07-30T17:37:31","date_gmt":"2014-07-30T15:37:31","guid":{"rendered":"http:\/\/realschule-eching.de\/cms\/?page_id=7685"},"modified":"2025-12-15T10:10:42","modified_gmt":"2025-12-15T09:10:42","slug":"elternbeirat","status":"publish","type":"page","link":"https:\/\/www.realschule-eching.de\/cms\/elternbeirat\/","title":{"rendered":"Elternbeirat 2025\/26 und 2026\/27"},"content":{"rendered":"\n<p>Seit Ende November 2025 ist ein neuer Elternbeirat f\u00fcr die Schuljahre 2025\/26 und 2026\/27 an der Imma-Mack-Realschule im Amt.<\/p>\n\n\n\n<p><em>Wir w\u00fcnschen allen Mitgliedern eine gute Amtszeit und freuen uns auf die Zusammenarbeit!<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/Elternbeirat-2025.jpg\" alt=\"\" class=\"wp-image-22017\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/Elternbeirat-2025.jpg 640w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/Elternbeirat-2025-80x60.jpg 80w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/Elternbeirat-2025-265x198.jpg 265w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/Elternbeirat-2025-560x420.jpg 560w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n<p><b>Mitglieder (alphabetisch):<\/b><br>Andrea Dannhauser, Bj\u00f6rn Formen, Barbara G\u00f6tz, Martin Kirsch, Sebastian Meyer, Miriam Nadler, Tobias Riemann, Sina Ruppe, Herbert Schmidt, Lucy Schmidt, Marco Stuckenberger, Marion Walting<\/p>\n<p><b>Vorsitz<\/b>: Andrea Dannhauser<\/p>\n<p><b>Stellvertretung<\/b>: Barbara G\u00f6tz<\/p>\n<p><b>Vertreter\/-in im Schulforum<\/b>: Andrea Dannhauser, Barbara G\u00f6tz, Martin Kirsch<\/p>\n<p><b>Ansprechpartner\/-innen f\u00fcr die Jahrgangsstufen: <\/b><\/p>\n<p>5. Klassen: Marco Stuckenberger<br>6. Klassen: Herbert Schmidt<br>7. Klassen: Marion Walting<br>8. Klassen: Sebastian Meyer<br>9. Klassen: Tobias Riemann<br>10. Klasse: Bj\u00f6rn Formen<\/p>\n<p>Adressenliste:&nbsp;<a href=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/Elternbeirat_Namensliste-2025-26-2026-27.pdf\">Elternbeirat_Adressenliste<\/a><\/p>\n<p>Kontakt: <a href=\"mailto:elternbeirat@realschule-eching.de\">elternbeirat@realschule-eching.de<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Aufgaben<\/strong><\/h3>\n<h4><strong>Was wir wollen?<\/strong><\/h4>\n<p>Wir engagieren uns mit konstruktiven Ideen, aber auch mit konstruktiver Kritik f\u00fcr ein harmonisches Schulleben. In unserer Schule sind Schulleitung, Lehrer und Elternbeirat eine Einheit. Wir alle wollen gemeinsam f\u00fcr das Wohl unserer Kinder sorgen. Daf\u00fcr stehen wir und freuen uns auf viele gemeinsame Ideen.<\/p>\n<h4><strong>Welche konkreten Aufgaben hat der Elternbeirat?<\/strong><\/h4>\n<p>Der Elternbeirat vertritt die gemeinsamen Interessen der Eltern:<\/p>\n<ul>\n<li>Er tr\u00e4gt der Schulleitung W\u00fcnsche, Anregungen und Verbesserungsvorschl\u00e4ge vor<\/li>\n<li>Er hilft bei organisatorischen, schulrechtlichen oder schulpolitischen Fragen<\/li>\n<li>Er versucht bei Problemen zwischen einzelnen Eltern und Lehrkr\u00e4ften zu vermitteln<\/li>\n<li>Er vergleicht den Schulalltag mit Elternbeir\u00e4ten anderer Schulen<\/li>\n<li>Er vertritt die Elternschaft der Realschule Eching bei internen und externen Veranstaltungen<\/li>\n<li>Der Elternbeirat setzt sich f\u00fcr die Anliegen der Sch\u00fcler\/-innen ein: Er vermittelt bei schwerwiegenden Problemen zwischen einzelnen Sch\u00fcler\/-innen und Lehrkr\u00e4ften. Er sieht sich als Anwalt der Sch\u00fcler\/-innen bei schwierigen sozialen oder disziplinarischen Fragen<\/li>\n<li>Er sammelt die Elternspende und gibt einzelnen Sch\u00fcler\/-innen finanzielle Unterst\u00fctzung. So werden teils Klassenfahrten, Ausstattungen, Projekte und Aktivit\u00e4ten, die mit normalen Etats nicht zu realisieren sind, \u201cgesponsert\u201d<\/li>\n<\/ul>\n<h4><strong>Was sind unsere Ziele als Elternbeirat?<\/strong><\/h4>\n<p>Partnerschaft in der Schule zwischen Lehrern und Eltern ist eine unabdingbare Voraussetzung, damit Eltern ihr Erziehungsrecht auch in Bezug auf die Schulausbildung ihrer Kinder wahrnehmen k\u00f6nnen. Leider zeigen Untersuchungen zum Schulalltag, dass die Mehrheit der Eltern die Schule nur als Aufgabe von Lehrern und Schulleitung wahrnimmt. Lediglich im Konfliktfall gehen einige wenige Eltern dar\u00fcber hinaus und wenden sich selbst mit Problemen und Fragen an die Schule oder an die jeweilige Lehrkraft. Eine aktive Beteiligung der Eltern an den Entscheidungen, die das Schulleben betreffen, ist aber Voraussetzung f\u00fcr die Identifikation der Sch\u00fcler und ihrer Familien mit ihrer Schule.<\/p>\n<h4><strong>Wie k\u00f6nnen wir unsere Aufgaben und Ziele umsetzen?<\/strong><\/h4>\n<p>Damit wir nicht nur unsere Mitsprache aus\u00fcben, sondern auch notwendige Ma\u00dfnahmen f\u00f6rdern k\u00f6nnen, werden wir durch Ihre Geld- und Sachspenden und Ihr Engagement unterst\u00fctzt. <strong>Bitte helfen Sie dabei mit!<\/strong><\/p>\n<h2>Rechtliche Grundlagen<\/h2>\n<h3>1. Wahl des Elternbeirats<\/h3>\n<p>Nach Art.66 BayEUG ist f\u00fcr je 50 Sch\u00fcler einer Schule ein Mitglied des Elternbeirats zu w\u00e4hlen. Er muss mindestens f\u00fcnf und h\u00f6chstens zw\u00f6lf Mitglieder haben. Die Wahl des Elternbeirats findet zu Beginn des jeweiligen Schuljahres statt. F\u00fcr jedes die Schule besuchende Kind wird ein Stimmzettel ausgegeben. Stimmberechtigt sind nur die bei der Wahl anwesenden Wahlberechtigten. Der Elternbeirat w\u00e4hlt aus seiner Mitte in der ersten Sitzung einen Vorsitzenden sowie dessen Stellvertreter. Die Amtszeit des Elternbeirats betr\u00e4gt zwei Jahre.<\/p>\n<h3>2. Aufgaben des Elternbeirats (nach Art.65 BayEUG)<\/h3>\n<ul>\n<li>das Vertrauensverh\u00e4ltnis zwischen den Eltern und den Lehrkr\u00e4ften, die gemeinsam f\u00fcr die Bildung und Erziehung der Sch\u00fcler verantwortlich sind, zu vertiefen<\/li>\n<li>\u00fcber W\u00fcnsche, Anregungen und Vorschl\u00e4ge der Eltern zu beraten<\/li>\n<li>Zustimmung bei der Entscheidung \u00fcber einen unterrichtsfreien Tag<\/li>\n<li>Mitspracherecht bei der Namensgebung der Schule<\/li>\n<\/ul>\n<h3>3. Rechte des Elternbeirats (Auszug)<\/h3>\n<p>Laut \u00a7 15 BaySchO ist die Zustimmung des Elternbeirats erforderlich f\u00fcr die Durchf\u00fchrung von Schullandheimaufenthalten, Schulskikursen, Lehr- und Studienfahrten sowie Fahrten im Rahmen eines internationalen Sch\u00fcleraustausches.<\/p>\n<ul>\n<li>Vorschl\u00e4ge und Anregungen zu grundlegenden organisatorischen Fragen des Unterrichtsbetriebs<\/li>\n<li>Durchf\u00fchrung von Veranstaltungen, die der Pflege und F\u00f6rderung der Gemeinschaftsarbeit von Schule und Elternhaus dienen<\/li>\n<li>Vorschl\u00e4ge und Anregungen zur schulischen Freizeitgestaltung<\/li>\n<li>Aufrechterhaltung der Ordnung in der Schule und der Verbesserung der \u00e4u\u00dferen Schulverh\u00e4ltnisse<\/li>\n<li>Mitspracherecht bei der Einf\u00fchrung neuer Lernmittel im Rahmen der Lernmittelfreiheit sowie die Ausstattung der Sch\u00fclerbibliothek<\/li>\n<li>Mitspracherecht bei grundlegenden Fragen der Erziehung in der Schule<\/li>\n<li>Mitspracherecht bei Fragen der Gesundheitspflege, der Berufsberatung, der Jugendf\u00fcrsorge und des Jugendschutzes im Rahmen der Schule<\/li>\n<li>Mitspracherecht bei der Einf\u00fchrung von Schulversuchen.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Seit Ende November 2025 ist ein neuer Elternbeirat f\u00fcr die Schuljahre 2025\/26 und 2026\/27 an der Imma-Mack-Realschule im Amt. Wir w\u00fcnschen allen Mitgliedern eine gute Amtszeit und freuen uns auf die Zusammenarbeit! Mitglieder (alphabetisch):Andrea Dannhauser, Bj\u00f6rn Formen, Barbara G\u00f6tz, Martin Kirsch, Sebastian Meyer, Miriam Nadler, Tobias Riemann, Sina Ruppe, Herbert Schmidt, Lucy Schmidt, Marco Stuckenberger, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-7685","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7685"}],"collection":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/comments?post=7685"}],"version-history":[{"count":43,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7685\/revisions"}],"predecessor-version":[{"id":22019,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/pages\/7685\/revisions\/22019"}],"wp:attachment":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media?parent=7685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}