{"id":21445,"date":"2024-08-01T22:19:49","date_gmt":"2024-08-01T20:19:49","guid":{"rendered":"https:\/\/www.realschule-eching.de\/cms\/?p=21445"},"modified":"2024-08-02T10:21:36","modified_gmt":"2024-08-02T08:21:36","slug":"projekttage-schule-fuers-leben-in-den-7-klassen","status":"publish","type":"post","link":"https:\/\/www.realschule-eching.de\/cms\/2024\/projekttage-schule-fuers-leben-in-den-7-klassen\/","title":{"rendered":"Projekttage \u201eSchule f\u00fcr\u2018s Leben\u201c in den 7. Klassen"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Alltagskompetenzen gewinnen und \u00fcber den Tellerrand schauen<\/strong><\/p>\n\n\n\n<p>Wieder mal in der vorletzten Schulwoche vom 15. bis zum 18. Juli 2024 konnten die Sch\u00fclerinnen und Sch\u00fcler der 7. Klassen \u00fcber die Handlungsfelder<\/p>\n\n\n\n<p>\u00b7 Ern\u00e4hrung<\/p>\n\n\n\n<p>\u00b7 Gesundheit und Sport<\/p>\n\n\n\n<p>\u00b7 Selbstbestimmtes Verbraucherverhalten<\/p>\n\n\n\n<p>\u00b7 Umweltverhalten und Nachhaltigkeit<\/p>\n\n\n\n<p>\u00b7 Digital handeln<\/p>\n\n\n\n<p>so Einiges erfahren. Die Projekttage \u201eSchule f\u00fcr\u2018s Leben\u201c wurden vom Bayerischen Staatsministerium f\u00fcr Unterricht und Kultus initiiert und finanziell unterst\u00fctzt, so dass gleich mehrere Experten in die Schule eingeladen werden konnten.<\/p>\n\n\n\n<p><strong>Vortrag zu Nahrungsmittelunvertr\u00e4glichkeiten<\/strong><\/p>\n\n\n\n<p>Die Apothekerin, Heilpraktikerin und Ern\u00e4hrungsberaterin Frau Koller berichtete \u00fcber Nahrungsmittelunvertr\u00e4glichkeiten und die Unterscheidung zu Allergien. Beispielsweise spricht man von Lactoseintoleranz (Milchzuckerunvertr\u00e4glichkeit), wenn der K\u00f6rper mit gr\u00f6\u00dferen Mengen Lactose Probleme hat, da er das Enzym Lactase zum Abbau nicht ausreichend herstellen kann. Wer auf Kuhmilch nicht verzichten will kann Tabletten mit dem Enzym Lactase einnehmen. Ansonsten k\u00f6nnen pflanzliche Alternativen (z.B. Hafermilch, Sojamilch) gew\u00e4hlt werden und besondere K\u00e4sesorten. Frau Koller warf auch einen kritischen Blick auf Lifestyle-Drogen als Doping f\u00fcr den Alltag.<\/p>\n\n\n\n<p><strong>Sporteinheit Doping und Fitness<\/strong><\/p>\n\n\n\n<p>Rund um Doping und Sport ging es in der Turnhalle bei der Sportlehrerin Frau Schmid. Die Fu\u00dfball-EM, die Tour de France und auch die anstehende Olympiade in Paris lassen Leistungssportler \u00fcber ihre Grenzen wachsen und so mancher fragt sich, ob da evtl. auch Chemie im Spiel ist. Die Sch\u00fclerinnen und Sch\u00fcler erfuhren Interessantes \u00fcber die Tests zum Doping. Im Anschluss an die Theorie war auch noch eine Sporteinheit geboten.<\/p>\n\n\n\n<p><strong>Energiesparendes Kochen<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7060.jpg\" alt=\"\" class=\"wp-image-21446\" style=\"width:356px;height:auto\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7060.jpg 1920w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7060-1536x1024.jpg 1536w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7060-696x464.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7060-1068x712.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7060-630x420.jpg 630w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p>Manche Sch\u00fclerinnen und Sch\u00fcler bekamen von Frau Schlesinger erstmals eine Einf\u00fchrung in die Schulk\u00fcche, um dort einen zum Sommer passenden Pausensnack zuzubereiten. Wer mochte konnte sich den selbst hergestellten Obstspie\u00df mit etwas Schokolade verfeinern. Als g\u00fcnstiger und erfrischender Drink wurde in k\u00fchles Leitungswasser frische Pfefferminze von der Kr\u00e4uterspirale und einige Zitronenscheiben gegeben.<\/p>\n\n\n\n<p>Wie die meisten schon w\u00e4hrend des Schuljahres im Fach Ern\u00e4hrung und Gesundheit und im Biologieunterricht erfahren haben macht\u2019s die bunte Mischung unserer Ern\u00e4hrung: ausreichend N\u00e4hrstoffe, gen\u00fcgend Vitamine, Mineralstoffe, Spurenelemente und sekund\u00e4re Pflanzenstoffe.<\/p>\n\n\n\n<p><strong>Ein Bauernhof zieht um<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1487\" height=\"1440\" data-id=\"21449\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111315.jpg\" alt=\"\" class=\"wp-image-21449\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111315.jpg 1487w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111315-696x674.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111315-1068x1034.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111315-434x420.jpg 434w\" sizes=\"(max-width: 1487px) 100vw, 1487px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1143\" height=\"1440\" data-id=\"21448\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111446.jpg\" alt=\"\" class=\"wp-image-21448\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111446.jpg 1143w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111446-696x877.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111446-1068x1346.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/20240716_111446-333x420.jpg 333w\" sizes=\"(max-width: 1143px) 100vw, 1143px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" data-id=\"21447\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/Foto-Gemueseacker.jpg\" alt=\"\" class=\"wp-image-21447\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/Foto-Gemueseacker.jpg 1920w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/Foto-Gemueseacker-1536x864.jpg 1536w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/Foto-Gemueseacker-696x392.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/Foto-Gemueseacker-1068x601.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/Foto-Gemueseacker-747x420.jpg 747w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Noch 2024 ist es soweit, dass der alte Bauernhof Pfl\u00fcgler die Hausnummer wechselt. Bei dem \u00fcber das Bayerische Fernsehen inzwischen ber\u00fchmten neuen Mega-Bau vor den Toren Neufahrns waren die Sch\u00fclerinnen und Sch\u00fcler mitten drin beim Entstehen eines riesigen modernen Bauernhofes. Frau Pfl\u00fcgler berichtete von ihrem Familienbetrieb und den kaufm\u00e4nnischen \u00dcberlegungen des direkten Verkaufs der Feldfr\u00fcchte im Hofladen. Denn neben dem Gem\u00fcse-, Zwiebel-, Kartoffel-, Braugerste- und Sojaacker werden auch in den zwei Treibh\u00e4usern neben Paprika und Tomaten sogar Melonen und Ingwer angebaut. Auch ein Hummelstock ist dort aufgestellt worden. Als Nutztiere werden Hennen und H\u00e4hne in einem massiv gebauten H\u00fchnerstall samt Wintergarten und Auslauf gehalten. Auf die Vorteile der Aufzucht und der Direktvermarktung von Eiern und H\u00e4hnchenfleisch auf dem Hof ging Frau Pfl\u00fcgler ein sowie auf das Thema Tierwohl. Sie brachte auch einen ihrer H\u00e4hne heraus, der als K\u00fcken \u00fcberleben durfte und keinen strapazi\u00f6sen Transport hinter sich hat. Beeindruckend war auch das fast fertiggestellte<\/p>\n\n\n\n<p>Wirtschaftshaus, in das in K\u00fcrze die Schlachterei, Gro\u00dfk\u00fcche, Brauerei und Bewirtungs- sowie Seminarr\u00e4ume einziehen sollen.<\/p>\n\n\n\n<p><strong>Leben im und vom M\u00fcll \u2013 Plastikm\u00fcll<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7070.jpg\" alt=\"\" class=\"wp-image-21450\" style=\"width:436px;height:auto\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7070.jpg 1920w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7070-1536x1024.jpg 1536w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7070-696x464.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7070-1068x712.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_7070-630x420.jpg 630w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p><strong>Wertsch\u00e4tze im Handy<\/strong><\/p>\n\n\n\n<p>In den Workshops zu den Themen M\u00fcll und Plastik \u201eTrash to cash\u201c und Smartphone \u201eGold sind sie uns wert\u201c unter Mitwirkung von Referentinnen von missio und Lehrkr\u00e4ften wurden die Sch\u00fclerinnen und Sch\u00fcler \u00fcber L\u00e4nder des globalen S\u00fcdens informiert. Erstaunlich empathisch versuchten sich die Zuh\u00f6rer in das Leben von Jugendlichen in den M\u00fcllkippen von Manila zu versetzen. Wenige haben sich bisher ernsthaft Gedanken \u00fcber den selbstproduzierten M\u00fcll gemacht. Thema bei den Smartphones waren die Herkunft der Materialien auf der ganzen Welt und die Wertsch\u00f6pfungskette. Reparatur und Recycling werden mehr und mehr Bedeutung beigemessen.<\/p>\n\n\n\n<p>Vorab reflektierten die Sch\u00fclerinnen und Sch\u00fcler mit Frau Bauer ihren Medienkonsum, generelle Kommunikation und sogar das Thema Cybergrooming wurde teils auch angesprochen.<\/p>\n\n\n\n<p>Wie kam es zu den M\u00fcllbergen? Damit besch\u00e4ftigte sich die Vorbereitung durch Frau Hohmann bzw. Frau Littel. Was M\u00fcllberge weltweit, selbst in den Meeren wachsen l\u00e4sst, ist unser Plastikm\u00fcll, der meist nicht abbaubar ist. Auch \u201efast fashion\u201c hat einen massiven Anteil. Um die bekanntesten Kunststoffe wie Polyethylen (PE), Polystyrol (PS), Polypropylen (PP) wiederverwerten zu k\u00f6nnen m\u00fcssten sie aufw\u00e4ndig getrennt werden und am besten sortenrein sein. Daher ist es besser Plastik wenn m\u00f6glich zu vermeiden und Alternativen zu nutzen.<\/p>\n\n\n\n<p>Andrea Littel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alltagskompetenzen gewinnen und \u00fcber den Tellerrand schauen Wieder mal in der vorletzten Schulwoche vom 15. bis zum 18. Juli 2024 konnten die Sch\u00fclerinnen und Sch\u00fcler der 7. Klassen \u00fcber die Handlungsfelder \u00b7 Ern\u00e4hrung \u00b7 Gesundheit und Sport \u00b7 Selbstbestimmtes Verbraucherverhalten \u00b7 Umweltverhalten und Nachhaltigkeit \u00b7 Digital handeln so Einiges erfahren. Die Projekttage \u201eSchule f\u00fcr\u2018s Leben\u201c [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":21450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[314,1,315,102],"tags":[],"class_list":["post-21445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2023-24","category-aktuelles","category-projekttage-7-klassen","category-schulleben"],"_links":{"self":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/21445"}],"collection":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/comments?post=21445"}],"version-history":[{"count":1,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/21445\/revisions"}],"predecessor-version":[{"id":21451,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/21445\/revisions\/21451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media\/21450"}],"wp:attachment":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media?parent=21445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/categories?post=21445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/tags?post=21445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}