{"id":21452,"date":"2024-07-29T22:42:47","date_gmt":"2024-07-29T20:42:47","guid":{"rendered":"https:\/\/www.realschule-eching.de\/cms\/?p=21452"},"modified":"2024-08-02T10:25:44","modified_gmt":"2024-08-02T08:25:44","slug":"ausstellung-zur-alkoholpraevention-an-der-imma-mack-realschule-eching","status":"publish","type":"post","link":"https:\/\/www.realschule-eching.de\/cms\/2024\/ausstellung-zur-alkoholpraevention-an-der-imma-mack-realschule-eching\/","title":{"rendered":"Ausstellung zur Alkoholpr\u00e4vention an der Imma-Mack-Realschule Eching"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1440\" data-id=\"21453\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67472.jpg\" alt=\"\" class=\"wp-image-21453\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67472.jpg 960w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67472-696x1044.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67472-280x420.jpg 280w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" data-id=\"21454\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67501.jpg\" alt=\"\" class=\"wp-image-21454\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67501.jpg 1920w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67501-1536x1024.jpg 1536w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67501-696x464.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67501-1068x712.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2024\/08\/IMG_67501-630x420.jpg 630w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Im Rahmen der diesj\u00e4hrigen Aktionswoche Alkohol wurde in der Imma-Mack-Realschule in Eching eine ganz besondere Ausstellung zur Alkoholpr\u00e4vention durchgef\u00fchrt.<\/p>\n\n\n\n<p>Die Imma-Mack-Realschule in Eching entschied sich in diesem Jahr, einen ganz besonderen Beitrag zur Alkoholpr\u00e4vention ihrer Sch\u00fclerinnen und Sch\u00fcler zu leisten: sie f\u00fchrte die Ausstellung des Bayerischen Zentrums f\u00fcr Pr\u00e4vention und Gesundheitsf\u00f6rderung (ZPG) \u201eSpa\u00df ohne Punkt und Koma\u201c durch. Alkohol und dessen Konsum sind in Deutschland bei Jugendlichen weit verbreitet und birgt einige k\u00f6rperliche, psychische und soziale Risiken in diesem Alter. Neun von zehn Jugendlichen von 16 &#8211; 17 Jahren haben bereits mindestens einmal Alkohol konsumiert.<\/p>\n\n\n\n<p>Um den Gefahren des fr\u00fchen Alkoholkonsums entgegenzuwirken, durften drei siebte sowie vier achte Klassen der Realschule die interaktive Ausstellung besuchen. \u201eSpa\u00df ohne Punkt und Koma\u201c wurde von drei Lehrerinnen und der Jugendsozialarbeiterin an der Schule durchgef\u00fchrt. Unterst\u00fctzt wurden sie von zwei Suchtpr\u00e4ventionsfachkr\u00e4ften vom Gesundheitsamt Freising und der Psychosozialen Beratungs- und Behandlungsstelle Prop e.V. Das Team hatte sich zuvor ausgiebig in die Themen der Ausstellung eingearbeitet. Dadurch konnten sie die Klassen an drei Schultagen in Kleingruppen durch die Informations- und Mitmach-Elemente der Ausstellung f\u00fchren. Die interaktiven Methoden erm\u00f6glichten einen spannenden Austausch und vielf\u00e4ltige Diskussionen rund um das Thema Alkoholkonsum und eine kritische Reflexion des eigenen Konsums. Die Erweiterung pers\u00f6nlicher Kompetenzen, ein verantwortungsvoller Umgang mit Alkohol und ein risikoarmer Konsum sollten gef\u00f6rdert werden.<\/p>\n\n\n\n<p>Insgesamt wurden w\u00e4hrend der Projektwoche 185 Sch\u00fclerinnen und Sch\u00fcler erreicht.<\/p>\n\n\n\n<p>Mit zahlreichen Veranstaltungen und Aktionen richtet sich die Aktionswoche Alkohol unter dem Motto \u201eAlkohol? Weniger ist besser!\u201c an eine breite \u00d6ffentlichkeit in ganz Deutschland. Sie findet alle zwei Jahre statt und verfolgt das Ziel, alle Menschen, die Alkohol trinken, \u00fcber die damit verbundenen Risiken sowie m\u00f6gliche Folgen zu informieren.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Sabrina Dietrich<\/p>\n\n\n\n<p>Gesundheitsamt Freising<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen der diesj\u00e4hrigen Aktionswoche Alkohol wurde in der Imma-Mack-Realschule in Eching eine ganz besondere Ausstellung zur Alkoholpr\u00e4vention durchgef\u00fchrt. Die Imma-Mack-Realschule in Eching entschied sich in diesem Jahr, einen ganz besonderen Beitrag zur Alkoholpr\u00e4vention ihrer Sch\u00fclerinnen und Sch\u00fcler zu leisten: sie f\u00fchrte die Ausstellung des Bayerischen Zentrums f\u00fcr Pr\u00e4vention und Gesundheitsf\u00f6rderung (ZPG) \u201eSpa\u00df ohne Punkt [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":21454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[314,1,102],"tags":[],"class_list":["post-21452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2023-24","category-aktuelles","category-schulleben"],"_links":{"self":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/21452"}],"collection":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/comments?post=21452"}],"version-history":[{"count":2,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/21452\/revisions"}],"predecessor-version":[{"id":21456,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/21452\/revisions\/21456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media\/21454"}],"wp:attachment":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media?parent=21452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/categories?post=21452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/tags?post=21452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}