{"id":22021,"date":"2025-12-19T10:08:16","date_gmt":"2025-12-19T09:08:16","guid":{"rendered":"https:\/\/www.realschule-eching.de\/cms\/?p=22021"},"modified":"2025-12-19T14:03:55","modified_gmt":"2025-12-19T13:03:55","slug":"alle-jahre-wieder","status":"publish","type":"post","link":"https:\/\/www.realschule-eching.de\/cms\/2025\/alle-jahre-wieder\/","title":{"rendered":"Alle Jahre wieder"},"content":{"rendered":"\n<p>Nicht schlecht gestaunt haben manche Sch\u00fclerinnen und Sch\u00fcler heute beim Betreten des Schulhauses: Frau Rosner (Klavier), Herr Goerge (Saxophon), Herr Bergdolt (Trompete), Frau Seeger (Klarinette), Herr Kaindl (Akkordeon) und Frau Scheeren (Querfl\u00f6te) empfingen die Sch\u00fclerinnen und Sch\u00fcler mit Advents- und Weihnachtsliedern. Der Applaus war riesig. Die Tradition, dass Lehrkr\u00e4fte am letzten Schultag vor Weihnachten Musik f\u00fcr unsere Sch\u00fclerinnen und Sch\u00fcler machen, besteht nun schon seit einigen Jahren. Manchmal in der Form eines &#8222;Lehrerchores&#8220; oder wie heute als Instrumentalensemble. Vielen Dank f\u00fcr diese sch\u00f6ne Geste!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1440\" src=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4.jpg\" alt=\"\" class=\"wp-image-22022\" srcset=\"https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4.jpg 1920w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4-1536x1152.jpg 1536w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4-80x60.jpg 80w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4-265x198.jpg 265w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4-696x522.jpg 696w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4-1068x801.jpg 1068w, https:\/\/www.realschule-eching.de\/cms\/wp-content\/uploads\/2025\/12\/4-560x420.jpg 560w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nicht schlecht gestaunt haben manche Sch\u00fclerinnen und Sch\u00fcler heute beim Betreten des Schulhauses: Frau Rosner (Klavier), Herr Goerge (Saxophon), Herr Bergdolt (Trompete), Frau Seeger (Klarinette), Herr Kaindl (Akkordeon) und Frau Scheeren (Querfl\u00f6te) empfingen die Sch\u00fclerinnen und Sch\u00fcler mit Advents- und Weihnachtsliedern. Der Applaus war riesig. Die Tradition, dass Lehrkr\u00e4fte am letzten Schultag vor Weihnachten Musik [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":22022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[321,1],"tags":[],"class_list":["post-22021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2025-26","category-aktuelles"],"_links":{"self":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/22021"}],"collection":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/comments?post=22021"}],"version-history":[{"count":2,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/22021\/revisions"}],"predecessor-version":[{"id":22026,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/posts\/22021\/revisions\/22026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media\/22022"}],"wp:attachment":[{"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/media?parent=22021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/categories?post=22021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.realschule-eching.de\/cms\/wp-json\/wp\/v2\/tags?post=22021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}